{"id":1442,"date":"2020-12-08T17:38:34","date_gmt":"2020-12-08T16:38:34","guid":{"rendered":"https:\/\/spiritualite.com\/blog\/?p=1442"},"modified":"2023-06-19T15:45:05","modified_gmt":"2023-06-19T13:45:05","slug":"tirage-du-yi-jing","status":"publish","type":"post","link":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/","title":{"rendered":"Yi Jing \u2013 Comment effectuer le tirage du Yi Jing ?"},"content":{"rendered":"\n<p>Peut-\u00eatre traversez-vous une p\u00e9riode de vie pleine d\u2019interrogations&nbsp;et ces questions vous sont-elles famili\u00e8res&nbsp;: dois-je changer de travail&nbsp;? Cette personne est-elle faite pour moi&nbsp;? La relation avec ma famille va-t-elle s\u2019apaiser&nbsp;? &nbsp;Ou peut-\u00eatre, avez-vous des questions plus concr\u00e8tes&nbsp;: dois-je d\u00e9velopper mon entreprise \u00e0 l\u2019international&nbsp;? Dois-je investir sur le web&nbsp;? Est-ce le bon moment pour faire ma demande en mariage&nbsp;? Ce mod\u00e8le de voiture va-t-il me convenir&nbsp;?<\/p>\n\n\n\n<p>Pour toutes ces questions, <strong>le Yi Jing peut vous accompagner \u00e0 aller vers ce qui est juste pour vous.<\/strong> Il ne vous dira pas quoi faire, ni ce qui va \u00eatre, il vous montrera ce que votre pr\u00e9sent r\u00e9v\u00e8le. Lorsqu\u2019un probl\u00e8me \u00e9merge, que vous butez face \u00e0 une situation ou que l\u2019inqui\u00e9tude s\u2019installe, avoir recours au Yi Jing permet d\u2019adopter une r\u00e9action adapt\u00e9e.<\/p>\n\n\n\n<p>Pour utiliser le Yi Jing, il est n\u00e9cessaire de proc\u00e9der \u00e0 un tirage. Ce dernier permet d\u2019\u00e9tablir un lien entre le probl\u00e8me constat\u00e9 et <a href=\"https:\/\/spiritualite.com\/blog\/yi-jing\/\">l\u2019un des 64 hexagrammes du Yi Jing<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Premi\u00e8re \u00e9tape&nbsp;du tirage : formuler la question<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pour d\u00e9marrer, formulez <strong>une question \u00e0 la premi\u00e8re personne contenant un verbe d\u2019action<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p>Cette \u00e9tape est tr\u00e8s importante. Prenez bien le temps de mener une r\u00e9flexion personnelle afin de bien identifier votre probl\u00e8me. Le fait de formuler votre question \u00e0 la premi\u00e8re personne va vous permettre de prendre la responsabilit\u00e9 de votre situation. Gr\u00e2ce \u00e0 cela, vous vous mettez en posture d\u2019action. C\u2019est vous et vous seul.e qui serez \u00e0 m\u00eame de prendre une d\u00e9cision, au regard des indications transmises par le Yi Jing.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Par exemple, \u00ab&nbsp;Comment am\u00e9liorer ma vie professionnelle&nbsp;?&nbsp;\u00bb devient \u00ab&nbsp;Comment puis-je am\u00e9liorer ma vie professionnelle&nbsp;? \u00bb<\/li>\n\n\n\n<li>\u00ab&nbsp;Comment en finir avec les probl\u00e8mes de couple&nbsp;?&nbsp;\u00bb devient \u00ab&nbsp;Dois-je entamer une th\u00e9rapie de couple avec mon compagnon\/ma compagne&nbsp;?&nbsp;\u00bb<\/li>\n<\/ul>\n\n\n\n<p>Votre question pose un cadre pr\u00e9cis, dans lequel la r\u00e9ponse du Yi Jing pourra \u00eatre interpr\u00e9t\u00e9e.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Si vous pr\u00e9voyez de faire appel au Yi Jing r\u00e9guli\u00e8rement, notez par \u00e9crit, \u00e0 chaque tirage, votre question et la date du tirage. <\/strong>Cela vous permettra de suivre l\u2019\u00e9volution de vos tirages et d\u2019en obtenir une vision globale.<\/li>\n\n\n\n<li><strong>Si votre question est une h\u00e9sitation entre deux possibilit\u00e9s, <\/strong>par exemple entre partir et rester, vous pouvez proc\u00e9der \u00e0 un tirage double. Pour cela, posez une question sp\u00e9cifique pour \u00ab&nbsp;partir&nbsp;\u00bb et une question sp\u00e9cifique pour \u00ab&nbsp;rester&nbsp;\u00bb. La comparaison des r\u00e9sultats vous aidera \u00e0 choisir la direction la plus juste pour vous. Par exemple, faites un premier tirage avec la question \u00ab&nbsp;Dois-je me s\u00e9parer de mon compagnon\/ma compagne&nbsp;?&nbsp;\u00bb et un deuxi\u00e8me avec la question \u00ab&nbsp;Dois-je donner une seconde chance \u00e0 mon couple&nbsp;?&nbsp;\u00bb<\/li>\n<\/ul>\n\n\n\n<p><strong>Rien ne sert de poser plus de 2 fois la m\u00eame question.<\/strong> Si la r\u00e9ponse ne vous satisfait pas, ce peut-\u00eatre pour 3 raisons&nbsp;:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>Vous avez mal pos\u00e9 la question, par exemple, votre question contient plusieurs questions cach\u00e9es<\/li>\n\n\n\n<li>Vous avez mal identifi\u00e9 votre probl\u00e9matique&nbsp;: ce qui vous questionne r\u00e9ellement n\u2019est pas la question que vous avez formul\u00e9e<\/li>\n\n\n\n<li>Vous ne souhaitez pas entendre la r\u00e9ponse que vous apporte le Yi Jing, car elle ne va pas dans le sens de ce que vous voulez entendre.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/spiritualite.com\/blog\/wp-content\/uploads\/2020\/12\/direction-choisir-tirage-yi-jing-1024x683.jpg\" alt=\"Yi_Jing\" class=\"wp-image-1445 lazyload\" width=\"523\" height=\"338\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 523px; --smush-placeholder-aspect-ratio: 523\/338;\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Deuxi\u00e8me \u00e9tape&nbsp;: proc\u00e9der au tirage<\/strong><\/h2>\n\n\n\n<p>Il existe deux mani\u00e8res de proc\u00e9der au tirage&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Avec 3 pi\u00e8ces de monnaie&nbsp;: technique plus rapide mais aussi plus exp\u00e9ditive<\/li>\n\n\n\n<li>Avec 50 baguettes d\u2019achill\u00e9e&nbsp;: technique plus lente mais qui apporte plus de pr\u00e9sence et d\u2019attention<\/li>\n<\/ul>\n\n\n\n<p>Dans cet article, nous allons aborder la m\u00e9thode des pi\u00e8ces.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La m\u00e9thode des pi\u00e8ces<\/h3>\n\n\n\n<p>Un tirage n\u00e9cessite trois pi\u00e8ces de monnaie de votre choix.<\/p>\n\n\n\n<ul class=\"wp-block-list\" type=\"1\">\n<li>Choisissez une face Yin et une face Yang pour chaque pi\u00e8ce. Yin correspond au pair et Yang \u00e0 l\u2019impair. Chaque face \u00e0 une valeur num\u00e9rique. Ce qui donne\u00a0:\n<ul class=\"wp-block-list\">\n<li>Yin = 2<\/li>\n\n\n\n<li>Yang = 3<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Lancez ensemble les trois pi\u00e8ces, comme vous le feriez pour lancer des d\u00e9s.<\/li>\n\n\n\n<li>Retranscrivez les faces sur lesquelles les pi\u00e8ces se sont arr\u00eat\u00e9es dans leur valeur num\u00e9rique puis additionnez les valeurs num\u00e9riques des pi\u00e8ces. Par exemple, si vous avez deux faces Ying et une face Yang, cela donne 2+2+3=7.<\/li>\n\n\n\n<li>Recommencez l\u2019op\u00e9ration 6 fois de suite. Vous obtenez ainsi 6 r\u00e9sultats.<\/li>\n<\/ul>\n\n\n\n<p>Les tirages permettent d\u2019obtenir quatre sortes de r\u00e9sultats&nbsp;: 6,7,8 ou 9. Chaque chiffre correspond \u00e0 un type de trait, comme vous pouvez le voir ci-dessous.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/spiritualite.com\/blog\/wp-content\/uploads\/2020\/12\/tableau-tirage-yi-jing.jpg\" alt=\"Tableau tirage yi jing traits\" class=\"wp-image-1448 lazyload\" width=\"548\" height=\"136\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 548px; --smush-placeholder-aspect-ratio: 548\/136;\" \/><\/figure>\n<\/div>\n\n\n<p>Un trait \u00ab&nbsp;mutant&nbsp;\u00bb (en violet) est un trait qui change de polarit\u00e9, de Yin \u00e0 Yang ou de Yang \u00e0 Yin. Un trait \u00ab&nbsp;stable&nbsp;\u00bb (en bleu) est un trait qui conserve la m\u00eame polarit\u00e9.<\/p>\n\n\n\n<p>Cette correspondance entre un chiffre et un trait va vous permettre de <strong>composer votre hexagramme<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reprenez vos 6 r\u00e9sultats. Prenez une feuille de papier. Dessinez le trait correspondant \u00e0 votre premier r\u00e9sultat.<\/li>\n\n\n\n<li>Puis, tracez le second trait, qui correspond \u00e0 votre second r\u00e9sultat, au-dessus du premier trait.&nbsp;Continuez ainsi en superposant les traits. Vous obtenez une figure \u00e0 6 traits.<\/li>\n\n\n\n<li>Ensuite, rendez-vous sur le tableau o\u00f9 tous les hexagrammes sont class\u00e9s (ci-dessous). D\u00e9couvrez le num\u00e9ro de votre hexagramme.<\/li>\n<\/ul>\n\n\n\n<p><strong>Si vous avez obtenu des traits mutants<\/strong>, \u00e7a se complique un petit peu.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reprenez les traits obtenus lors du tirage, en rempla\u00e7ant les traits mutants par des traits de polarit\u00e9 inverse&nbsp;: vieux Yin est remplac\u00e9 par jeune Yang et vieux Yang est remplac\u00e9 par jeune Ying.<\/li>\n\n\n\n<li>Cela forme un nouvel hexagramme, que l\u2019on appelle <strong>hexagramme de perspective<\/strong>. Retrouvez dans le tableau le num\u00e9ro de ce nouvel hexagramme. L\u2019hexagramme de perspective apporte un \u00e9clairage sur les particularit\u00e9s de la situation qui vous pr\u00e9occupe.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/spiritualite.com\/blog\/wp-content\/uploads\/2020\/12\/tableau-hexagrammes.jpg\" alt=\"Hexagramme_Yi_Jing\" class=\"wp-image-1444 lazyload\" width=\"563\" height=\"443\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 563px; --smush-placeholder-aspect-ratio: 563\/443;\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Hexagramme_Yi_Jing\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/fr.wikipedia.org\/wiki\/Hexagramme_Yi_Jing<\/a><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Troisi\u00e8me \u00e9tape&nbsp;: analyser et interpr\u00e9ter &nbsp;<\/h2>\n\n\n\n<p>Les textes du Yi Jing peuvent paraitre d\u00e9concertants, et c\u2019est bien normal&nbsp;! Mais ne vous alarmez pas, ils vont vous d\u00e9livrer leur signification. Au d\u00e9part, ne cherchez pas \u00e0 r\u00e9pondre imm\u00e9diatement \u00e0 la question pos\u00e9e. Rassemblez dans un premier temps les \u00e9l\u00e9ments permettant de comprendre comment la situation est d\u00e9crite.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Observez les figures de votre hexagramme<\/strong>. La forme de l\u2019hexagramme vous parle-t-elle&nbsp;? Y a-t-il autant de Yin et de Yang&nbsp;? Y a-t-il un trait plus mis en valeur dans l\u2019hexagramme, car il est le seul \u00e0 \u00eatre comme cela&nbsp;?<\/li>\n\n\n\n<li><strong>Focalisez votre attention sur le nom de l\u2019hexagramme. <\/strong>Ce nom englobe \u00e0 la fois la description de la situation et le comportement que cette derni\u00e8re implique. Laissez infuser ce mot en vous pour voir ce qu\u2019il vous \u00e9voque.<\/li>\n\n\n\n<li><strong>Ensuite, plusieurs possibilit\u00e9s s\u2019offrent \u00e0 vous.<\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>Si vous avez un exemplaire d\u2019une \u00e9dition comment\u00e9e du Yi Jing<\/strong> chez vous ou que vous pouvez vous en procurer un&nbsp;: lisez la partie du texte du Yi Jing qui y est reli\u00e9e \u00e0 votre hexagramme. Lisez notamment la partie intitul\u00e9e <em>le Jugement<\/em>, qui est l\u2019appr\u00e9ciation globale de la figure et la partie nomm\u00e9e <em>la Grande Image<\/em>, qui est l\u2019exemple de l\u2019attitude \u00e0 observer dans votre situation.<\/p>\n\n\n\n<p><strong>Vous pouvez relativement facilement trouver des analyses sur internet <\/strong>de chaque hexagramme. N\u00e9anmoins, soyez prudent. <a href=\"https:\/\/spiritualite.com\/blog\/yi-jing\/\">Le Yi Jing<\/a> est un texte tr\u00e8s ancien r\u00e9dig\u00e9 en chinois. Il peut \u00eatre ais\u00e9 d\u2019en faire une interpr\u00e9tation erron\u00e9e ou trop simpliste. N\u2019oubliez pas que le Yi Jing vous permet d\u2019identifier les potentialit\u00e9s que vous offre le moment pr\u00e9sent et non de vous pr\u00e9dire de mani\u00e8re pr\u00e9cise votre avenir.<\/p>\n\n\n\n<p><strong>Pour un tirage plus approfondi, faites appel \u00e0 un professionnel<\/strong>, qui vous accompagnera dans la compr\u00e9hension des textes et de leur signification.<\/p>\n\n\n\n<p><strong>Dans tous les cas, laissez infuser en vous les textes que vous lisez.<\/strong> Voyez ce que \u00e7a \u00e9voque pour vous, \u00e0 quoi \u00e7a fait naturellement \u00e9cho. Prenez le temps de philosopher un peu. Les textes du Yi Jing ne sont pas \u00e0 prendre au pied de la lettre. Chaque terme a une signification. C\u2019est celle-ci qui vous guidera. Vous verrez alors apparaitre de nouveaux possibles, certains vous encourageront, d\u2019autres seront plus difficiles \u00e0 accepter. Ce sera alors \u00e0 vous de d\u00e9cider quel chemin emprunter.<\/p>\n\n\n\n<p>Avez-vous d\u00e9j\u00e0 fait appel au Yi Jing pour vous aider dans votre quotidien ?  &nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<div class=\"row recommended\"><div class=\"col-md-3\">\n    <a href=\"#?fromblog\">\n        <div style=\"display: block;\n   position: relative;\">\n            <img decoding=\"async\" class=\"img-fluid lazyload\" data-src=\"https:\/\/spiritualite.com\/assets\/images\/public\/6\/6X\/6XobetRazjFREz5Q\/offers\/LVhfrj2fBzYjalJD_255_190.png\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/>\n        <\/div>\n    <\/a>\n    <div class=\"inner-slider\">\n        <div class=\"inner-wrapper\">\n            <div class=\"d-flex align-items-center\">\n                <span class=\"seller-image\">\n               <img decoding=\"async\" class=\"img-fluid lazyload\"\n                    data-src=\"https:\/\/spiritualite.com\/assets\/images\/spiritualite\/favicon.png\"\n                    alt='Compte d\u00e9sactiv\u00e9' src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/>\n\n               <\/span>\n                <span class=\"seller-name\">Compte d\u00e9sactiv\u00e9<\/span>\n            <\/div>\n            <a href=\"#?fromblog\"><h3 class=\"service-min-height\">Je r\u00e9ponds \u00e0 vos probl\u00e9matique de vie en vous initiant \u00e0 l'oracle du Yi Jing<\/h3><\/a>\n            <div class=\"content-info\">\n\n                <div class=\"rating-wrapper d-none\">\n                  <span class=\"gig-rating text-body-2\">\n                     <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1792 1792\" width=\"15\" height=\"15\">\n                        <path fill=\"currentColor\"\n                              d=\"M1728 647q0 22-26 48l-363 354 86 500q1 7 1 20 0 21-10.5 35.5t-30.5 14.5q-19 0-40-12l-449-236-449 236q-22 12-40 12-21 0-31.5-14.5t-10.5-35.5q0-6 2-20l86-500-364-354q-25-27-25-48 0-37 56-46l502-73 225-455q19-41 49-41t49 41l225 455 502 73q56 9 56 46z\">\n                        <\/path>\n                     <\/svg>\n                     0                     <span>(0)<\/span>\n                  <\/span>\n                <\/div>\n                <span class=\"user-info-rating d-flex\">\n                                <span class=\"total-rating-out-five text-orange pr-1\">&nbsp;<\/span>\n                <span class=\"total-rating text-muted\">&nbsp;<\/span>\n                            <\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Peut-\u00eatre traversez-vous une p\u00e9riode de vie pleine d\u2019interrogations&nbsp;et ces questions vous sont-elles famili\u00e8res&nbsp;: dois-je changer de travail&nbsp;? Cette personne est-elle faite pour moi&nbsp;? La relation avec ma famille va-t-elle s\u2019apaiser&nbsp;? &nbsp;Ou peut-\u00eatre, avez-vous des questions plus concr\u00e8tes&nbsp;: dois-je d\u00e9velopper mon entreprise \u00e0 l\u2019international&nbsp;? Dois-je investir sur le web&nbsp;? Est-ce le bon moment pour faire ma [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":4991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[65],"tags":[310,309,307,308],"class_list":{"0":"post-1442","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-spiritualite","8":"tag-tirage-du-yi-jing","9":"tag-tirage-du-yijing","10":"tag-yi-jing","11":"tag-yijing"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yi Jing \u2013 Comment effectuer le tirage du Yi Jing ? -<\/title>\n<meta name=\"description\" content=\"Le tirage du Yi Jing \u00e9tablit un lien entre votre probl\u00e8me et l&#039;un des 64 hexagrammes. Il vous permet d&#039;adopter une r\u00e9action adapt\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yi Jing \u2013 Comment effectuer le tirage du Yi Jing ? -\" \/>\n<meta property=\"og:description\" content=\"Le tirage du Yi Jing \u00e9tablit un lien entre votre probl\u00e8me et l&#039;un des 64 hexagrammes. Il vous permet d&#039;adopter une r\u00e9action adapt\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Spiritualite.com\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-08T16:38:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-19T13:45:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spiritualite.com\/blog\/wp-content\/uploads\/2020\/12\/pexels-magda-ehlers-2846034.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1279\" \/>\n\t<meta property=\"og:image:height\" content=\"697\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucile Joan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucile Joan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/\"},\"author\":{\"name\":\"Lucile Joan\",\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/#\\\/schema\\\/person\\\/81db6b63ae05d3ce218b50c4a1257396\"},\"headline\":\"Yi Jing \u2013 Comment effectuer le tirage du Yi Jing ?\",\"datePublished\":\"2020-12-08T16:38:34+00:00\",\"dateModified\":\"2023-06-19T13:45:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/\"},\"wordCount\":1456,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/pexels-magda-ehlers-2846034.jpg\",\"keywords\":[\"tirage du yi jing\",\"tirage du yijing\",\"yi jing\",\"yijing\"],\"articleSection\":[\"Spiritualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/\",\"url\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/\",\"name\":\"Yi Jing \u2013 Comment effectuer le tirage du Yi Jing ? -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/pexels-magda-ehlers-2846034.jpg\",\"datePublished\":\"2020-12-08T16:38:34+00:00\",\"dateModified\":\"2023-06-19T13:45:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/#\\\/schema\\\/person\\\/81db6b63ae05d3ce218b50c4a1257396\"},\"description\":\"Le tirage du Yi Jing \u00e9tablit un lien entre votre probl\u00e8me et l'un des 64 hexagrammes. Il vous permet d'adopter une r\u00e9action adapt\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/pexels-magda-ehlers-2846034.jpg\",\"contentUrl\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/pexels-magda-ehlers-2846034.jpg\",\"width\":1279,\"height\":697,\"caption\":\"le yi jing\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/tirage-du-yi-jing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spiritualit\u00e9\",\"item\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/spiritualite\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Yi Jing \u2013 Comment effectuer le tirage du Yi Jing ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/\",\"name\":\"Blog Spiritualite.com\",\"description\":\"Le Blog Spirituel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/#\\\/schema\\\/person\\\/81db6b63ae05d3ce218b50c4a1257396\",\"name\":\"Lucile Joan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b56ccf8fc4bedbc2c297df7de2afe962e4368e9c81ed5d044b84ddb8603dbca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b56ccf8fc4bedbc2c297df7de2afe962e4368e9c81ed5d044b84ddb8603dbca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b56ccf8fc4bedbc2c297df7de2afe962e4368e9c81ed5d044b84ddb8603dbca?s=96&d=mm&r=g\",\"caption\":\"Lucile Joan\"},\"description\":\"Passionn\u00e9e par de multiples sujets et curieuse de nature, j'adore \u00e9crire, la nature, l'alimentation et la spiritualit\u00e9.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/lucile-joan\\\/\"],\"url\":\"https:\\\/\\\/spiritualite.com\\\/blog\\\/author\\\/lucile-joan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yi Jing \u2013 Comment effectuer le tirage du Yi Jing ? -","description":"Le tirage du Yi Jing \u00e9tablit un lien entre votre probl\u00e8me et l'un des 64 hexagrammes. Il vous permet d'adopter une r\u00e9action adapt\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/","og_locale":"fr_FR","og_type":"article","og_title":"Yi Jing \u2013 Comment effectuer le tirage du Yi Jing ? -","og_description":"Le tirage du Yi Jing \u00e9tablit un lien entre votre probl\u00e8me et l'un des 64 hexagrammes. Il vous permet d'adopter une r\u00e9action adapt\u00e9e.","og_url":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/","og_site_name":"Blog Spiritualite.com","article_published_time":"2020-12-08T16:38:34+00:00","article_modified_time":"2023-06-19T13:45:05+00:00","og_image":[{"width":1279,"height":697,"url":"https:\/\/spiritualite.com\/blog\/wp-content\/uploads\/2020\/12\/pexels-magda-ehlers-2846034.jpg","type":"image\/jpeg"}],"author":"Lucile Joan","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lucile Joan","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/#article","isPartOf":{"@id":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/"},"author":{"name":"Lucile Joan","@id":"https:\/\/spiritualite.com\/blog\/#\/schema\/person\/81db6b63ae05d3ce218b50c4a1257396"},"headline":"Yi Jing \u2013 Comment effectuer le tirage du Yi Jing ?","datePublished":"2020-12-08T16:38:34+00:00","dateModified":"2023-06-19T13:45:05+00:00","mainEntityOfPage":{"@id":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/"},"wordCount":1456,"commentCount":0,"image":{"@id":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/#primaryimage"},"thumbnailUrl":"https:\/\/spiritualite.com\/blog\/wp-content\/uploads\/2020\/12\/pexels-magda-ehlers-2846034.jpg","keywords":["tirage du yi jing","tirage du yijing","yi jing","yijing"],"articleSection":["Spiritualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/","url":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/","name":"Yi Jing \u2013 Comment effectuer le tirage du Yi Jing ? -","isPartOf":{"@id":"https:\/\/spiritualite.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/#primaryimage"},"image":{"@id":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/#primaryimage"},"thumbnailUrl":"https:\/\/spiritualite.com\/blog\/wp-content\/uploads\/2020\/12\/pexels-magda-ehlers-2846034.jpg","datePublished":"2020-12-08T16:38:34+00:00","dateModified":"2023-06-19T13:45:05+00:00","author":{"@id":"https:\/\/spiritualite.com\/blog\/#\/schema\/person\/81db6b63ae05d3ce218b50c4a1257396"},"description":"Le tirage du Yi Jing \u00e9tablit un lien entre votre probl\u00e8me et l'un des 64 hexagrammes. Il vous permet d'adopter une r\u00e9action adapt\u00e9e.","breadcrumb":{"@id":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/#primaryimage","url":"https:\/\/spiritualite.com\/blog\/wp-content\/uploads\/2020\/12\/pexels-magda-ehlers-2846034.jpg","contentUrl":"https:\/\/spiritualite.com\/blog\/wp-content\/uploads\/2020\/12\/pexels-magda-ehlers-2846034.jpg","width":1279,"height":697,"caption":"le yi jing"},{"@type":"BreadcrumbList","@id":"https:\/\/spiritualite.com\/blog\/tirage-du-yi-jing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/spiritualite.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Spiritualit\u00e9","item":"https:\/\/spiritualite.com\/blog\/spiritualite\/"},{"@type":"ListItem","position":3,"name":"Yi Jing \u2013 Comment effectuer le tirage du Yi Jing ?"}]},{"@type":"WebSite","@id":"https:\/\/spiritualite.com\/blog\/#website","url":"https:\/\/spiritualite.com\/blog\/","name":"Blog Spiritualite.com","description":"Le Blog Spirituel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spiritualite.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/spiritualite.com\/blog\/#\/schema\/person\/81db6b63ae05d3ce218b50c4a1257396","name":"Lucile Joan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2b56ccf8fc4bedbc2c297df7de2afe962e4368e9c81ed5d044b84ddb8603dbca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2b56ccf8fc4bedbc2c297df7de2afe962e4368e9c81ed5d044b84ddb8603dbca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b56ccf8fc4bedbc2c297df7de2afe962e4368e9c81ed5d044b84ddb8603dbca?s=96&d=mm&r=g","caption":"Lucile Joan"},"description":"Passionn\u00e9e par de multiples sujets et curieuse de nature, j'adore \u00e9crire, la nature, l'alimentation et la spiritualit\u00e9.","sameAs":["https:\/\/www.linkedin.com\/in\/lucile-joan\/"],"url":"https:\/\/spiritualite.com\/blog\/author\/lucile-joan\/"}]}},"fimg_url":"https:\/\/spiritualite.com\/blog\/wp-content\/uploads\/2020\/12\/pexels-magda-ehlers-2846034.jpg","_links":{"self":[{"href":"https:\/\/spiritualite.com\/blog\/wp-json\/wp\/v2\/posts\/1442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spiritualite.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spiritualite.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spiritualite.com\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/spiritualite.com\/blog\/wp-json\/wp\/v2\/comments?post=1442"}],"version-history":[{"count":8,"href":"https:\/\/spiritualite.com\/blog\/wp-json\/wp\/v2\/posts\/1442\/revisions"}],"predecessor-version":[{"id":4992,"href":"https:\/\/spiritualite.com\/blog\/wp-json\/wp\/v2\/posts\/1442\/revisions\/4992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spiritualite.com\/blog\/wp-json\/wp\/v2\/media\/4991"}],"wp:attachment":[{"href":"https:\/\/spiritualite.com\/blog\/wp-json\/wp\/v2\/media?parent=1442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spiritualite.com\/blog\/wp-json\/wp\/v2\/categories?post=1442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spiritualite.com\/blog\/wp-json\/wp\/v2\/tags?post=1442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}